{"id":113029,"date":"2005-11-08T00:00:00","date_gmt":"2005-11-07T23:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/gite-de-taures-2\/"},"modified":"2026-09-02T03:30:10","modified_gmt":"2026-09-02T01:30:10","slug":"gite-de-taures-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/gite-de-taures-2\/","title":{"rendered":"H\u00fctte Taures"},"content":{"rendered":"<p>Abseits der sommerlichen Menschenmassen erwarten Sie in diesem Bauernhaus in den Landes mit seiner warmen Holzvert\u00e4felung Ruhe und Erholung. Es liegt in der N\u00e4he des Waldes, 7 km von den Str\u00e4nden des Bassin und 15 km vom See Cazaux Sanguinet sowie vom Ozean entfernt.<br \/>\nM\u00f6glichkeit, M\u00e4rchenabende oder -wanderungen zu organisieren.  Kostenlose Einf\u00fchrung in Tai Chi Chuan auf Anfrage.<br \/>\nEntdecken Sie die Austernzucht mit dem Maison de l'Hu\u00eetre in Gujan-Mestras, das spannende interaktive Animationen anbietet. Rundherum bieten Str\u00e4nde, Angeln, Bootsausfl\u00fcge, Wanderungen und Radtouren sowie unber\u00fchrte Landschaften jedem die M\u00f6glichkeit, seine Freizeit abwechslungsreich zu gestalten.<br \/>\nETAGE: 3 Einzelbetten, 1 Doppelbett.<br \/>\nErdgeschoss: Wohnzimmer, Sitzecke, Schlafsofa f\u00fcr 2 Personen, DVD-Player. K\u00fcche, Geschirrsp\u00fcler, Mikrowelle. Badezimmer, Waschmaschine, WC. \u00dcberdachte Terrasse. Garten, Gartenm\u00f6bel, Grill, Tischtennisplatte. Heizung inbegriffen.<\/p>","protected":false},"featured_media":227832,"template":"","villeh":[2168],"type-hebergement":[2184],"class_list":["post-113029","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c.jpg",1200,799,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c-768x511.jpg",768,511,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c.jpg",1200,799,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c.jpg",1200,799,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6c35809a399ccd413e08dda7e320396c-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A l&rsquo;\u00e9cart des foules estivales, calme et tranquillit\u00e9 vous attendent dans cette ferme landaise aux boiseries chaleureuses. Proche de la for\u00eat, elle est \u00e0 7 km des plages du Bassin [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113029\/revisions"}],"predecessor-version":[{"id":196500,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113029\/revisions\/196500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/227832"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=113029"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=113029"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=113029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}