{"id":113267,"date":"2006-03-23T00:00:00","date_gmt":"2006-03-22T23:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/gite-casa-rosa-2\/"},"modified":"2026-09-02T03:30:35","modified_gmt":"2026-09-02T01:30:35","slug":"ferienhaus-casa-rosa-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/gite-casa-rosa-2\/","title":{"rendered":"Ferienhaus Casa Rosa"},"content":{"rendered":"<p>G\u00eete T2 f\u00fcr 2 Personen, Erdgeschoss, in der N\u00e4he des Eigent\u00fcmers, unabh\u00e4ngiger Eingang, privater Garten mit B\u00e4umen, Au\u00dfenparkplatz am Haus.<br \/>\nWohnbereich mit Einbauk\u00fcche, Cerankochfeld, Pyrolyse-Backofen, K\u00fchl-Gefrierkombination, Mikrowelle, Essbereich, Sitzecke mit nicht ausklappbarem Schlafsofa, Fernseher, Stereoanlage und Stauraum.<br \/>\nWC, Badezimmer mit begehbarer Dusche, Waschmaschine.<br \/>\nZimmer mit einem Bett (160 \u00d7 200 cm) und Fernseher, Schreibtisch, Stauraum.<br \/>\n\u00dcberdachte Pergola mit Gartenm\u00f6beln, Relax, Sofa.<br \/>\nKostenloses Wifi. \u00dcberdachung f\u00fcr Fahrr\u00e4der. Einbahnstra\u00dfe und auf 30 km\/h begrenzt.<\/p>","protected":false},"featured_media":252060,"template":"","villeh":[2168],"type-hebergement":[2184],"class_list":["post-113267","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-eb1d2af515fa935df3d2773339f788de-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"G\u00eete T2 pour 2 personnes, RDC, \u00e0 proximit\u00e9 du propri\u00e9taire, entr\u00e9e ind\u00e9pendante, jardin priv\u00e9 arbor\u00e9, parking ext\u00e9rieur pr\u00e8s de la maison. Pi\u00e8ce de vie comprenant cuisine \u00e9quip\u00e9e, plaque vitro c\u00e9ramique, [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":4,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113267\/revisions"}],"predecessor-version":[{"id":251400,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113267\/revisions\/251400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/252060"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=113267"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=113267"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=113267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}