{"id":113779,"date":"2013-04-09T13:51:05","date_gmt":"2013-04-09T11:51:05","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/monsieur-manuel-martin-2\/"},"modified":"2026-09-02T03:31:13","modified_gmt":"2026-09-02T01:31:13","slug":"herr-manuel-martin-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/monsieur-manuel-martin-2\/","title":{"rendered":"Herr Manuel MARTIN"},"content":{"rendered":"<p>Dieses Apartment mit einem Schlafzimmer befindet sich im 2. Stock mit Aufzug im Stadtzentrum von Arcachon und verf\u00fcgt \u00fcber ein Wohnzimmer mit ausgestatteter K\u00fcchenzeile, einen Essbereich mit Tisch und St\u00fchlen sowie eine BZ-Sitzbank und einen Fernseher.<br \/>\nDas Schlafzimmer verf\u00fcgt \u00fcber ein Doppelbett und einen Kleiderschrank. Das Badezimmer verf\u00fcgt \u00fcber eine Dusche, ein Waschbecken und ein WC.<br \/>\nDer Balkon ist mit Gartenm\u00f6beln, zwei Liegen und einer Markise ausgestattet.<br \/>\nEs stehen Optionen zur Verf\u00fcgung, z.\u00a0B. ein W\u00e4schereistandort und Parkpl\u00e4tze in der N\u00e4he. Ein klappbares Babybett ist ebenfalls erh\u00e4ltlich. Urlaubsgutscheine werden akzeptiert.<\/p>","protected":false},"featured_media":274171,"template":"","villeh":[2167],"type-hebergement":[2184],"class_list":["post-113779","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-arcachon","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8.jpg",420,639,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8-394x600.jpg",394,600,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8.jpg",420,639,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8.jpg",420,639,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8.jpg",420,639,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8.jpg",420,639,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-2d61e850d0c1c9f0666e6eaa88f81ce8-8x12.jpg",8,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Cet appartement T2, situ\u00e9 au 2\u00e8me \u00e9tage avec ascenseur en plein centre ville d&rsquo;Arcachon, comprend un s\u00e9jour avec kitchenette \u00e9quip\u00e9e, un espace repas avec table et chaises, ainsi qu&rsquo;une banquette [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113779\/revisions"}],"predecessor-version":[{"id":115424,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113779\/revisions\/115424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/274171"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=113779"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=113779"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=113779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}