{"id":113957,"date":"2014-10-29T09:31:18","date_gmt":"2014-10-29T08:31:18","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/monsieur-pierre-mirc-2\/"},"modified":"2026-09-02T03:31:29","modified_gmt":"2026-09-02T01:31:29","slug":"herr-pierre-mirc-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/monsieur-pierre-mirc-2\/","title":{"rendered":"Herr Pierre Mirc"},"content":{"rendered":"<p>M\u00f6blierte Touristenunterkunft mit 3 Sternen!<br \/>\nENR 330090000834E<\/p>\n<p>Gro\u00dfe 30 m\u00b2 gro\u00dfe Studioh\u00fctte, sehr sauber, Boulevard de la Plage, 40 Meter vom Strand entfernt! <\/p>\n<p>Diese Wohnung ist im sehr komfortablen skandinavischen Stil eingerichtet. Sie befindet sich im Erdgeschoss einer ruhigen und sicheren Residenz (Gegensprechanlage). Sie ist sehr hell und besteht aus zwei Zimmern, darunter einer separaten Kabine. Das Bad und die Toilette sind vom Wohnzimmer aus zug\u00e4nglich. Die Wohnung verf\u00fcgt \u00fcber WLAN-Internetzugang.<br \/>\nUnser Markenzeichen ist die Sauberkeit der Wohnung, deren M\u00f6bel und Geschirr sich in einwandfreiem Zustand befinden. Bettw\u00e4sche und Handt\u00fccher sind im Preis inbegriffen. In der Saison nur wochenweise Vermietung von Samstag bis Samstag. In der Nebensaison mindestens 4 N\u00e4chte.<br \/>\nFahrradabstellplatz in der Residenz. \u00dcberdachter Parkplatz 30 Meter entfernt vorhanden.<\/p>","protected":false},"featured_media":265394,"template":"","villeh":[2167],"type-hebergement":[2184],"class_list":["post-113957","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-arcachon","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a.jpeg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a-150x150.jpeg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a-600x450.jpeg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a-768x576.jpeg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a.jpeg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a.jpeg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a.jpeg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-d7eb7fd7f313260ba28dc98446ef285a-16x12.jpeg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Meubl\u00e9 de tourisme 3 \u00e9toiles ! ENR 330090000834E Grand Studio Cabine de 30 m\u00b2, tr\u00e8s propre, boulevard de la Plage, \u00e0 40 m\u00e8tres de la plage ! Cet appartement est [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113957\/revisions"}],"predecessor-version":[{"id":128311,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/113957\/revisions\/128311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/265394"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=113957"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=113957"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=113957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}