{"id":114761,"date":"2018-01-30T14:39:40","date_gmt":"2018-01-30T13:39:40","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/oha-west-2\/"},"modified":"2026-09-02T03:32:32","modified_gmt":"2026-09-02T01:32:32","slug":"oha-west-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/oha-west-2\/","title":{"rendered":"Ach Westen"},"content":{"rendered":"<p>Oha WEST \u2013 Ein Kokon in der untergehenden Sonne, der vom Gesang der V\u00f6gel geweckt wird.<br \/>\nSie befinden sich in unmittelbarer N\u00e4he des Radweges, der Gesch\u00e4fte und des Strandes von Graveyron.<\/p>","protected":false},"featured_media":220588,"template":"","villeh":[2164],"type-hebergement":[2184],"class_list":["post-114761","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00.jpeg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00-150x150.jpeg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00-600x450.jpeg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00-768x576.jpeg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00-1024x768.jpeg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00.jpeg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00.jpeg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ed42bb8da91edce0705eb3fa3280bf00-16x12.jpeg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Oha WEST &#8211; Un cocon au soleil couchant r\u00e9veill\u00e9 par le chant des oiseaux. Vous serez \u00e0 proximit\u00e9 imm\u00e9diate de la piste cyclable, des commerces et de la plage de [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/114761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/114761\/revisions"}],"predecessor-version":[{"id":115506,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/114761\/revisions\/115506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/220588"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=114761"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=114761"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=114761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}