{"id":115194,"date":"2019-08-14T17:02:54","date_gmt":"2019-08-14T15:02:54","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/village-du-falgouet-petit-chalet-5-6-personnes-2\/"},"modified":"2026-09-02T03:33:26","modified_gmt":"2026-09-02T01:33:26","slug":"dorf-falgouet-kleines-chalet-5-6-personen-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/village-du-falgouet-petit-chalet-5-6-personnes-2\/","title":{"rendered":"Village du Falgou\u00ebt \u2013 Kleines Chalet f\u00fcr 5\/6 Personen"},"content":{"rendered":"<p> Kleines Chalet f\u00fcr 5\/6 Personen, zertifiziert mit dem Europ\u00e4ischen Umweltzeichen f\u00fcr Tourismus und Behinderung im Jahr 2019.<br \/>\nLe Falgou\u00ebt ist ein \u00d6ko-Solidarit\u00e4tsdorf, das Fischerh\u00fctten \u00e4hnelt und an einem au\u00dfergew\u00f6hnlichen Ort am Rande der Bassin von Arcachon mit direktem Zugang zum Strand liegt.<br \/>\nDie 8 Chalets f\u00fcgen sich perfekt in die Umgebung ein. Ein angelegter Garten im Einklang mit der lokalen Flora schm\u00fcckt die Chalets und f\u00fchrt Urlauber zum Strand.<br \/>\nDie Seite steht allen offen. Es nimmt auch kleine Gruppen auf, denen nach den vom Verein festgelegten Bedingungen ein Mehrzweckraum zur Verf\u00fcgung stehen kann.<br \/>\nDie Chalets sind komplett m\u00f6bliert und mit Haushaltsger\u00e4ten ausgestattet.<br \/>\nGanzj\u00e4hrig ge\u00f6ffnet. ANCV-Urlaubsgutscheine werden akzeptiert.<br \/>\nDer Fu\u00dfweg am Ende des Gartens f\u00fchrt Falgou\u00ebt-Benutzer zum Jacht- und Fischereihafen, zu Gesch\u00e4ften und zu lokalen Aktivit\u00e4ten.<\/p>","protected":false},"featured_media":260687,"template":"","villeh":[2170],"type-hebergement":[2184],"class_list":["post-115194","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-01967b410f0d574724de4626b26965d2-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Petit chalet 5\/6 personnes labellis\u00e9 Ecolabel Europ\u00e9en Tourisme et Handicap en 2019. Le Falgou\u00ebt est un village \u00e9co-solidaire aux allures de cabanes de p\u00eacheurs, implant\u00e9 sur un site exceptionnel en [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/115194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/115194\/revisions"}],"predecessor-version":[{"id":115543,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/115194\/revisions\/115543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/260687"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=115194"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=115194"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=115194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}