{"id":239980,"date":"2005-06-29T00:00:00","date_gmt":"2005-06-28T22:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/hotel-villa-teranga\/"},"modified":"2026-09-02T03:05:31","modified_gmt":"2026-09-02T01:05:31","slug":"hotel-villa-teranga","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/hotel-villa-teranga\/","title":{"rendered":"Hotel Villa Teranga"},"content":{"rendered":"<p>Das Hotel Villa Teranga liegt am Radweg im Stadtzentrum von Andernos-les-Bains, weniger als 5 Gehminuten vom Strand entfernt. Es verf\u00fcgt \u00fcber eine Terrasse, auf der Sie sich bei einem Getr\u00e4nk entspannen k\u00f6nnen. <\/p>\n<p>Alle Zimmer im Hotel Villa Teranga sind elegant und modern eingerichtet und verf\u00fcgen \u00fcber einen Flachbild-TV, kostenfreies WLAN und ein eigenes Bad mit kostenlosen Pflegeprodukten.  <\/p>\n<p>Morgens wird in der Villa Teranga ein kontinentales Fr\u00fchst\u00fccksbuffet serviert, das Sie im Speisesaal oder im Freien genie\u00dfen k\u00f6nnen. Die Unterkunft verf\u00fcgt \u00fcber eine Bar und die Restaurants der Stadt erreichen Sie in wenigen Minuten zu Fu\u00df. <\/p>\n<p>Die Lage des Hotels Villa Teranga macht es zu einem ausgezeichneten Ausgangspunkt, um den Bassin von Arcachon zu erkunden.<\/p>","protected":false},"featured_media":260858,"template":"","villeh":[2170],"type-hebergement":[2183],"class_list":["post-239980","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-hotels"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf.jpg",600,435,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-cebe2a58bb627d3e2ae0e2e766b5a4cf-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Situ\u00e9 le long de la piste cyclable, dans le centre ville d&rsquo;Andernos-les-Bains, \u00e0 moins de 5 minutes \u00e0 pied de la plage, l&rsquo;h\u00f4tel Villa Teranga poss\u00e8de une terrasse o\u00f9 vous [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/239980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/239980\/revisions"}],"predecessor-version":[{"id":240488,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/239980\/revisions\/240488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/260858"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=239980"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=239980"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=239980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}