{"id":59677,"date":"2007-06-06T17:11:08","date_gmt":"2007-06-06T15:11:08","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/hotel-cote-sable\/"},"modified":"2026-09-02T03:05:39","modified_gmt":"2026-09-02T01:05:39","slug":"sandkustenhotel","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/hotel-cote-sable\/","title":{"rendered":"Sandy-Side-Hotel"},"content":{"rendered":"<p>Am Strandboulevard von Cap Ferret, gegen\u00fcber der D\u00fcne Pilat, liegt das Hotel C\u00f4t\u00e9 Sable **** und seine gro\u00dfe Terrasse mit Blick auf die Bucht sind von der Architektur der \u00f6rtlichen H\u00fctten inspiriert. Der Besitzer des Ortes wollte verschiedene Universen, damit \u201edie Leute immer wieder an die C\u00f4t\u00e9 Sable kommen, ohne sich jemals daran sattzusehen.\u201c Holz und Naturmaterialien dominieren die Zimmer des Cap Ferret, die Arcachonnaises haben den eleganten Look alter Art-Deco-Villen, die zeitgen\u00f6ssischen vereinen Design und warme Farben. 5 Zimmer bieten Blick auf den Teich, 10 weitere blicken auf die G\u00e4rten und verf\u00fcgen \u00fcber private Terrassen. Der Concierge-Service k\u00fcmmert sich um Restaurantreservierungen, Transfers vom Flughafen zum Bahnhof sowie um die Vermietung von Fahrr\u00e4dern und Elektroautos f\u00fcr Reisen rund um die Halbinsel. Ein \u201eBy Clarins\u201c-SPA verf\u00fcgt \u00fcber einen Whirlpool, ein Hamam und einen Behandlungsraum, der das ganze Jahr \u00fcber ge\u00f6ffnet ist.<\/p>","protected":false},"featured_media":270634,"template":"","villeh":[2166],"type-hebergement":[2183],"class_list":["post-59677","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-hotels"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a.jpg",1000,1404,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a-427x600.jpg",427,600,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a-768x1078.jpg",768,1078,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a-729x1024.jpg",729,1024,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a.jpg",1000,1404,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a.jpg",1000,1404,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/08\/sirtaqui-382aed4d5e51b1c69adbcfcccdc8b06a-9x12.jpg",9,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Boulevard de la plage au Cap Ferret, face \u00e0 la dune du Pilat, l\u2019h\u00f4tel C\u00f4t\u00e9 Sable **** et sa grande terrasse vue bassin, s\u2019inspire de l\u2019architecture des cabanes du pays. [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59677\/revisions"}],"predecessor-version":[{"id":61007,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59677\/revisions\/61007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/270634"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=59677"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=59677"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=59677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}