{"id":59714,"date":"2008-10-15T10:47:12","date_gmt":"2008-10-15T08:47:12","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/halte-nocturne-de-lherbe\/"},"modified":"2026-09-02T03:00:14","modified_gmt":"2026-09-02T01:00:14","slug":"nachtstopp-im-gras","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/halte-nocturne-de-lherbe\/","title":{"rendered":"Nachtstopp in L\u2019Herbe"},"content":{"rendered":"<p>Nachtstopp mit kostenlosem Parken von 20:00 bis 09:00 Uhr, begrenzt auf 48 Stunden. liegt an der D106 300 m nach dem Kreisverkehr im Dorf L&#039;Herbe. <\/p>","protected":false},"featured_media":218650,"template":"","villeh":[2166],"type-hebergement":[2179],"class_list":["post-59714","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-aires-de-camping-cars"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-749da33dc91cf6225aa4d534be6c3ccd-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Halte nocturne avec stationnement gratuit autoris\u00e9 de 20h \u00e0 9h, limit\u00e9 \u00e0 48h. situ\u00e9e sur la D106 \u00e0 300 m apr\u00e8s le rond point du village de L&rsquo;Herbe.","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59714\/revisions"}],"predecessor-version":[{"id":60965,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59714\/revisions\/60965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/218650"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=59714"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=59714"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=59714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}