{"id":59717,"date":"2015-06-18T09:43:32","date_gmt":"2015-06-18T07:43:32","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/aire-des-3-coccinelles\/"},"modified":"2026-09-02T03:00:16","modified_gmt":"2026-09-02T01:00:16","slug":"bereich-von-3-marienkafern","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/de\/hebergement\/aire-des-3-coccinelles\/","title":{"rendered":"Bereich der 3 Marienk\u00e4fer"},"content":{"rendered":"<p>Viele Leistungen f\u00fcr einen perfekten Aufenthalt! <\/p>\n<p>\u2013 Strom an allen Standorten, 2 Entw\u00e4sserungsbereiche<br \/>\n\u2013 1 Waschsalon<br \/>\n\u2013 1 \u201eBio\u201c-Lebensmittelladen f\u00fcr Notf\u00e4lle, mit jeden Morgen frischem Brot und Geb\u00e4ck.<br \/>\n\u2013 Kostenloses WLAN-Netzwerk<br \/>\n\u2013 Petanque-Platz<br \/>\n\u2013 Video\u00fcberwachung<\/p>\n<p>Anreise jederzeit m\u00f6glich mit Automatenterminal und CB. 24\/7<\/p>\n<p>GPS-Koordinaten<br \/>\nDD \/ 44.6190278 \/ DMS N 44\u00b037&#039;08.5\u2033 W 1\u00b0 05&#039;54.6\u2033<\/p>","protected":false},"featured_media":227239,"template":"","villeh":[2168],"type-hebergement":[2179],"class_list":["post-59717","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-aires-de-camping-cars"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-ca01a6a999b43aed672e12caf77f26b0-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"De nombreux services pour un s\u00e9jour parfait ! &#8211; \u00c9lectricit\u00e9 \u00e0 tous les emplacements, 2 zones de vidange &#8211; 1 laverie automatique &#8211; 1 \u00e9picerie \u00ab\u00a0bio\u00a0\u00bb de d\u00e9pannage, avec pain [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59717\/revisions"}],"predecessor-version":[{"id":60968,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/hebergement\/59717\/revisions\/60968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/227239"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=59717"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/villeh?post=59717"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/type-hebergement?post=59717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}