{"id":59733,"date":"2024-08-31T15:45:36","date_gmt":"2024-08-31T13:45:36","guid":{"rendered":"https:\/\/bassin-arcachon.com\/se-deplacer-sur-le-bassin\/locations-velo\/ginette\/"},"modified":"2026-09-02T04:45:44","modified_gmt":"2026-09-02T02:45:44","slug":"ginette","status":"publish","type":"velo_cpt","link":"https:\/\/bassin-arcachon.com\/de\/se-deplacer-sur-le-bassin\/locations-velo\/ginette\/","title":{"rendered":"Ginette"},"content":{"rendered":"<p>Ben\u00f6tigen Sie ein klassisches Fahrrad, ein Elektrofahrrad oder einen Elektroroller? Ginette am B\u00e9lisaire-Pier in Cap Ferret verf\u00fcgt \u00fcber eine gro\u00dfe Produktpalette und bietet verschiedene Pakete an, die von einem halben Tag bis zu einer Woche reichen.<\/p>","protected":false},"featured_media":223477,"template":"","ville":[2162],"class_list":["post-59733","velo_cpt","type-velo_cpt","status-publish","has-post-thumbnail","hentry","ville-lege-cap-ferret"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-fdf54d7bc0170cab776ca772e80e24b9-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Vous avez besoin d&rsquo;un v\u00e9lo classique, d&rsquo;un v\u00e9lo \u00e9lectrique ou d&rsquo;un triporteur \u00e9lectrique ? Ginette, \u00e0 la jet\u00e9e B\u00e9lisaire au Cap Ferret, poss\u00e8de une large gamme de produits et propose [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/velo_cpt\/59733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/velo_cpt"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/types\/velo_cpt"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/velo_cpt\/59733\/revisions"}],"predecessor-version":[{"id":60654,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/velo_cpt\/59733\/revisions\/60654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media\/223477"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/media?parent=59733"}],"wp:term":[{"taxonomy":"ville","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/de\/wp-json\/wp\/v2\/ville?post=59733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}