{"id":59559,"date":"2020-11-25T18:35:09","date_gmt":"2020-11-25T17:35:09","guid":{"rendered":"https:\/\/bassin-arcachon.com\/se-deplacer-sur-le-bassin\/locations-velo\/a-leau-velo\/"},"modified":"2026-09-02T04:45:31","modified_gmt":"2026-09-02T02:45:31","slug":"water-bike","status":"publish","type":"velo_cpt","link":"https:\/\/bassin-arcachon.com\/en\/se-deplacer-sur-le-bassin\/locations-velo\/a-leau-velo\/","title":{"rendered":"Water Bike"},"content":{"rendered":"<p>Bike rental only with free delivery to your place of stay in Arcachon, Pyla-sur-Mer, Le Moulleau, La Teste de Buch. (VTC bikes, electric bikes, children&#039;s bikes).<br \/>\nWe deliver the bikes and pick them up from your home!<br \/>\nReservation possible.<br \/>\nNo children&#039;s bikes, but child bike seats available.<\/p>","protected":false},"featured_media":260833,"template":"","ville":[2156],"class_list":["post-59559","velo_cpt","type-velo_cpt","status-publish","has-post-thumbnail","hentry","ville-arcachon"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038.jpg",800,803,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038-598x600.jpg",598,600,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038-768x771.jpg",768,771,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038.jpg",800,803,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038.jpg",800,803,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038.jpg",800,803,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-63717d892bdefc464619a7073145e038-12x12.jpg",12,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Location de v\u00e9los uniquement en livraison gratuite sur votre lieu de s\u00e9jour \u00e0 Arcachon, le Pyla-sur-Mer, Le Moulleau, La Teste de Buch. (v\u00e9los VTC, v\u00e9los \u00e9lectriques, v\u00e9los enfants). Nous livrons [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/velo_cpt\/59559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/velo_cpt"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/types\/velo_cpt"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/velo_cpt\/59559\/revisions"}],"predecessor-version":[{"id":59562,"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/velo_cpt\/59559\/revisions\/59562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/media\/260833"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/media?parent=59559"}],"wp:term":[{"taxonomy":"ville","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/en\/wp-json\/wp\/v2\/ville?post=59559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}