{"id":113566,"date":"2009-10-19T16:17:17","date_gmt":"2009-10-19T14:17:17","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/villa-seabird-2\/"},"modified":"2026-09-02T03:30:54","modified_gmt":"2026-09-02T01:30:54","slug":"villa-seabird-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/villa-seabird-2\/","title":{"rendered":"Villa Seabird"},"content":{"rendered":"<p>Los nombres de las calles marcan el tono: \u00abAll\u00e9e de la Pin\u00e8de\u00bb, \u00abAll\u00e9e du Rendez-vous\u00bb, \u00abAll\u00e9e des Bambous\u00bb\u2026 \u00a1Es aqu\u00ed, al borde del bosque, a apenas unos 800 metros del centro de Cap Ferret, donde te espera tu destino de vacaciones! Las dos habitaciones, decoradas con buen gusto, cuentan con terrazas bajo los pinos y acceso directo a la piscina. La anfitriona, Sylvie, es una aut\u00e9ntica sibarita y sus desayunos se convierten r\u00e1pidamente en toda una fiesta. Tambi\u00e9n son una ocasi\u00f3n para charlar sobre los lugares imprescindibles de la pen\u00ednsula, las puestas de sol sobre el oc\u00e9ano o los paseos por el bosque. Para guardar el picnic que hab\u00e9is preparado para la excursi\u00f3n en barco, hay una nevera a vuestra disposici\u00f3n, as\u00ed como una cuna de viaje para el peque\u00f1o que se ha quedado olvidado en casa. Para aligerar el equipaje, Sylvie tambi\u00e9n os presta toallas de playa.<\/p>","protected":false},"featured_media":219597,"template":"","villeh":[2166],"type-hebergement":[2181],"class_list":["post-113566","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-chambres-dhotes"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac.jpg",496,330,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-8bbe6ca75b6f7103e15168ff017ed3ac-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le nom des rues donne le ton : all\u00e9e de la \u00abPin\u00e8de\u00bb, du \u00abrendez-vous\u00bb, des \u00abBambous\u00bb\u2026 C\u2019est ici, en lisi\u00e8re de for\u00eat, \u00e0 quelques 800 m\u00e8tres \u00e0 peine du centre [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113566\/revisions"}],"predecessor-version":[{"id":115404,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113566\/revisions\/115404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/219597"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=113566"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=113566"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=113566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}