{"id":113723,"date":"2013-01-02T14:01:23","date_gmt":"2013-01-02T13:01:23","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/vacances-esprit-cabanes-2\/"},"modified":"2026-09-02T03:31:10","modified_gmt":"2026-09-02T01:31:10","slug":"vacaciones-espiritu-cabanas-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/vacances-esprit-cabanes-2\/","title":{"rendered":"Vacaciones en Esp\u00edritu de Cabanes"},"content":{"rendered":"<p>Cerca del bosque, este alojamiento amueblado para 2 personas le acerca al murmullo de las olas del Bassin de Arcachon. Tambi\u00e9n podr\u00e1 llegar al puerto y a las actividades ostricolas o festivas en solo unos pasos.<br \/>\nLa comodidad sencilla pero funcional de la casa, tanto en verano como en invierno (calefacci\u00f3n el\u00e9ctrica), le permitir\u00e1 recargar energ\u00edas tras las m\u00faltiples actividades que le ofrecen Andernos-les-Bains y sus alrededores: ba\u00f1os, paseos por las marismas, ciclismo por los carriles bici, compras en la calle peatonal, diversas actividades n\u00e1uticas y la imprescindible visita a las playas oce\u00e1nicas de Grand Crohot...<\/p>","protected":false},"featured_media":248551,"template":"","villeh":[2170],"type-hebergement":[2184],"class_list":["post-113723","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cb51d3b55b33413eec91828bf589a6c7-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Proche de la for\u00eat, ce meubl\u00e9 2 personnes vous rapproche du clapotis des vaguelettes du Bassin d&rsquo;Arcachon. Vous rejoindrez aussi le Port et les animations ostr\u00e9icoles ou festives \u00e0 deux [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113723\/revisions"}],"predecessor-version":[{"id":188572,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/113723\/revisions\/188572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/248551"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=113723"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=113723"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=113723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}