{"id":114851,"date":"2018-05-11T14:24:35","date_gmt":"2018-05-11T12:24:35","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/locaplage-18-studio-bidaou-plain-pied-2\/"},"modified":"2026-09-02T03:32:43","modified_gmt":"2026-09-02T01:32:43","slug":"locaplage-18-estudio-bidaou-bungalow-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/locaplage-18-studio-bidaou-plain-pied-2\/","title":{"rendered":"Ubicaci\u00f3n 18: Estudio de una sola planta \u201cBidaou\u201d"},"content":{"rendered":"<p>Alquiler de vacaciones situado entre Arcachon y L\u00e8ge Cap-Ferret y a 30 minutos de Burdeos y sus vi\u00f1edos.<\/p>\n<p>Idealmente situado en el coraz\u00f3n de la Bassin de Arcachon, en el pueblo de Taussat, en el municipio de Lanton, podr\u00e1 aprovechar su estancia, rodeado de naturaleza, para explorar la Bassin de Arcachon.<\/p>\n<p>Podr\u00e1 descubrir libremente los lugares clave de los municipios de Arcachon, La teste de Buch, Gujan-Mestras, le Teich, Biganos, Audenge, Andernos, Ar\u00e8s y L\u00e8ge Cap-Ferret, como la Duna de Pyla, el Faro de Cap- Hur\u00f3n, etc\u2026<\/p>\n<p>Tambi\u00e9n podr\u00e1 disfrutar de los numerosos paseos a pie o en bicicleta, excursiones que se ofrecen desde la casa rural o sus alrededores.<\/p>","protected":false},"featured_media":220696,"template":"","villeh":[2164],"type-hebergement":[2184],"class_list":["post-114851","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Location de vacances situ\u00e9 entre Arcachon et L\u00e8ge Cap-Ferret et \u00e0 30 minutes de Bordeaux et de ses vignobles. Id\u00e9alement situ\u00e9 au Coeur du Bassin d&rsquo;Arcachon dans le village de [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/114851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/114851\/revisions"}],"predecessor-version":[{"id":115516,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/114851\/revisions\/115516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/220696"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=114851"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=114851"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=114851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}