{"id":115014,"date":"2019-01-24T16:07:59","date_gmt":"2019-01-24T15:07:59","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/studio-ancien-chai-2\/"},"modified":"2026-09-02T03:33:16","modified_gmt":"2026-09-02T01:33:16","slug":"antiguo-estudio-en-bodega-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/studio-ancien-chai-2\/","title":{"rendered":"Antiguo estudio de bodega"},"content":{"rendered":"<p>Val\u00e9rie les da la bienvenida a esta encantadora bodega antigua con piedra vista. Este estudio totalmente equipado tiene capacidad para cuatro personas.<br \/>\nCon su terraza y peque\u00f1o jard\u00edn equipado con barbacoa, podr\u00e1 disfrutar de los placeres de las comidas al aire libre o tomar el sol con total tranquilidad.<br \/>\nLa ciudad de Teich, ciudad elegida por la naturaleza, le ofrecer\u00e1 un entorno de vida ideal con sus carriles bici, su santuario de aves y su peque\u00f1o puerto deportivo.<\/p>","protected":false},"featured_media":220869,"template":"","villeh":[2169],"type-hebergement":[2184],"class_list":["post-115014","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-le-teich","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-6b46e6d0164d7fecee2299f7fd8114ce-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Val\u00e9rie vous accueille dans cet ancien chai plein de charme avec pierres apparentes, ce studio parfaitement \u00e9quip\u00e9 peut accueillir jusqu\u2019\u00e0 quatre personnes. Avec sa terrasse et son jardinet \u00e9quip\u00e9 d&rsquo;un [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115014\/revisions"}],"predecessor-version":[{"id":115528,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115014\/revisions\/115528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/220869"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=115014"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=115014"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=115014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}