{"id":115022,"date":"2019-02-20T10:15:01","date_gmt":"2019-02-20T09:15:01","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/la-cabane-des-laban-appartement-2-2\/"},"modified":"2026-09-02T03:33:17","modified_gmt":"2026-09-02T01:33:17","slug":"la-cabane-des-laban-apartamento-2-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/la-cabane-des-laban-appartement-2-2\/","title":{"rendered":"La Caba\u00f1a Laban \u2013 apartamento 2"},"content":{"rendered":"<p>Con los pies en el agua, en el pintoresco entorno del puerto de Larros, nuestra caba\u00f1a puede alquilarse por un m\u00ednimo de 4 noches. <\/p>\n<p>Construido siguiendo el esp\u00edritu de las caba\u00f1as Bassin de Arcachon, el apartamento, situado en la primera planta de la caba\u00f1a, dispone de una magn\u00edfica terraza de 12 m\u00b2 que da al lago e ilumina el sal\u00f3n, y tiene capacidad para 4 personas (1 de ellas en el dormitorio principal).<\/p>","protected":false},"featured_media":228079,"template":"","villeh":[2168],"type-hebergement":[2184],"class_list":["post-115022","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3.jpg",1067,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3-600x337.jpg",600,337,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3-768x432.jpg",768,432,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3.jpg",1067,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3.jpg",1067,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d23c668b15d05eb32484f3d1692376b3-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Les pieds dans l&rsquo;eau, dans l&rsquo;ambiance pittoresque du port de Larros, notre cabane se loue pour 4 nuits minimum. Construit dans l&rsquo;esprit des cabanes du Bassin d&rsquo;Arcachon, l&rsquo;appartement, situ\u00e9 au [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115022\/revisions"}],"predecessor-version":[{"id":139445,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115022\/revisions\/139445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/228079"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=115022"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=115022"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=115022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}