{"id":115281,"date":"2019-12-17T10:45:14","date_gmt":"2019-12-17T09:45:14","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/villa-titoune-2\/"},"modified":"2026-09-02T03:33:33","modified_gmt":"2026-09-02T01:33:33","slug":"villa-titoune-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/villa-titoune-2\/","title":{"rendered":"Villa Titoune"},"content":{"rendered":"<p>Villa con car\u00e1cter, al borde del bosque, rodeada por un jard\u00edn paisaj\u00edstico completamente cerrado (1000 m2)<br \/>\nUna ex\u00f3tica caba\u00f1a de madera, convertida en un acogedor dormitorio con ba\u00f1o, adem\u00e1s de un estanque con tortugas y peces de colores, completan este entorno natural.<br \/>\nRenovada en 2019 por un dise\u00f1ador de interiores, Villa Titoune le ofrece todo el confort y el equipamiento para una estancia perfecta en familia o con amigos.<br \/>\nEn 5 minutos en bicicleta llegar\u00e1s a las playas de Bassin (\u00a1ah, los aperitivos al atardecer!), al campo de golf de Aiguilles Vertes o al aut\u00e9ntico y tranquilo pueblo de Taussat, con su antiguo puerto y sus tiendas tradicionales. El cercano carril bici le llevar\u00e1 en 10 minutos al centro de Andernos, con su mercado cubierto, sus calles peatonales, su paseo mar\u00edtimo y sus numerosos y animados establecimientos.<\/p>","protected":false},"featured_media":275258,"template":"","villeh":[2164],"type-hebergement":[2184],"class_list":["post-115281","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca.jpeg",1200,626,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca-150x150.jpeg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca-600x313.jpeg",600,313,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca-768x401.jpeg",768,401,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca-1024x534.jpeg",1024,534,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca.jpeg",1200,626,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca.jpeg",1200,626,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/09\/sirtaqui-5e83ae2f41261194a05b25ad3646d0ca-18x9.jpeg",18,9,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Villa de caract\u00e8re, en lisi\u00e8re de for\u00eat, entour\u00e9e d\u2019un jardin paysag\u00e9 enti\u00e8rement clos (1000 m2) Une cabane de bois exotique, am\u00e9nag\u00e9e en douillette chambre avec salle d\u2019eau, ainsi qu\u2019un bassin [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115281\/revisions"}],"predecessor-version":[{"id":115550,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115281\/revisions\/115550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/275258"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=115281"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=115281"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=115281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}