{"id":115647,"date":"2020-06-12T14:17:56","date_gmt":"2020-06-12T12:17:56","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/le-bout-de-lestey-2\/"},"modified":"2026-09-02T03:34:03","modified_gmt":"2026-09-02T01:34:03","slug":"le-bout-de-lestey-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/le-bout-de-lestey-2\/","title":{"rendered":"El fin de los Estey"},"content":{"rendered":"<p>A 800 m de la piscina y de la finca CERTES, a 300 m de la panader\u00eda y del intermarch\u00e9, a 150 m del carril bici. Zona muy tranquila<br \/>\nEste alojamiento CON AIRE ACONDICIONADO compuesto por 1 dormitorio con cama de 160 cm, 1 sala de estar con cocina equipada y un c\u00f3modo sof\u00e1 convertible para 2 personas, 1 ba\u00f1o con 1 cabina de ducha\/lavabo\/WC se encuentra en nuestra propiedad pero es completamente independiente. y no pasado por alto<br \/>\n2 bicicletas para adultos disponibles e incluidas en el precio.<\/p>","protected":false},"featured_media":234243,"template":"","villeh":[2164],"type-hebergement":[2184],"class_list":["post-115647","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100.jpg",1200,803,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100-600x402.jpg",600,402,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100-768x514.jpg",768,514,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100-1024x685.jpg",1024,685,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100.jpg",1200,803,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100.jpg",1200,803,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/02\/sirtaqui-2cf8f5d2bee4e39f3cee32cb64559100-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00e0 800 m du bassin de baignade et du domaine de CERTES, \u00e0 300 m de la boulangerie et d&rsquo;intermarch\u00e9 , \u00e0 150 m de la piste cyclable. Quartier tr\u00e8s [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115647\/revisions"}],"predecessor-version":[{"id":117483,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/115647\/revisions\/117483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/234243"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=115647"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=115647"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=115647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}