{"id":116081,"date":"2021-10-29T11:26:36","date_gmt":"2021-10-29T09:26:36","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/le-margouillat-2\/"},"modified":"2026-09-02T03:34:23","modified_gmt":"2026-09-02T01:34:23","slug":"el-geco-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/le-margouillat-2\/","title":{"rendered":"La Margouillat"},"content":{"rendered":"<p>Acceso a la propiedad a trav\u00e9s de una puerta segura, con estacionamiento exclusivo.<br \/>\nEl chalet dispone de un sal\u00f3n con cocina equipada y una zona de estar (sof\u00e1 cama).<br \/>\nEl dormitorio tiene una cama de 160 cm y un armario.<br \/>\nDucha a ras de suelo en ba\u00f1o y WC.<br \/>\nTerraza privada con muebles de jard\u00edn.<br \/>\nCerca del carril bici, de una parada de autob\u00fas y de la estaci\u00f3n de tren de Hume.<br \/>\nSituado a 1 km del Bassin de Arcachon y de los parques de ocio.<\/p>","protected":false},"featured_media":228178,"template":"","villeh":[2168],"type-hebergement":[2184],"class_list":["post-116081","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b.jpg",1200,1603,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-449x600.jpg",449,600,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-768x1026.jpg",768,1026,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-767x1024.jpg",767,1024,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-1150x1536.jpg",1150,1536,true],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b.jpg",1200,1603,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-cb98164befc9f5b5bb55a8079b27784b-9x12.jpg",9,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Acc\u00e8s \u00e0 la propri\u00e9t\u00e9 par un portail s\u00e9curis\u00e9, avec parking d\u00e9di\u00e9. Le chalet comporte une pi\u00e8ce \u00e0 vivre avec cuisine \u00e9quip\u00e9e et un coin salon (canap\u00e9 convertible). La chambre est [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116081\/revisions"}],"predecessor-version":[{"id":190294,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116081\/revisions\/190294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/228178"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=116081"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=116081"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=116081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}