{"id":116517,"date":"2022-10-29T17:15:03","date_gmt":"2022-10-29T15:15:03","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/la-cabane-de-valerie\/"},"modified":"2026-09-02T03:34:45","modified_gmt":"2026-09-02T01:34:45","slug":"la-cabana-de-valerie","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/la-cabane-de-valerie\/","title":{"rendered":"La caba\u00f1a de Val\u00e9rie"},"content":{"rendered":"<p>Bonita casa de 100 m\u00b2, de una sola planta y totalmente renovada, de 3 estrellas, con un jard\u00edn vallado y arbolado de 750 m\u00b2. Se encuentra al norte de la Bassin, en el municipio de Andernos-les-Bains, entre la punta de Cap-Ferret y la cuenca sur, cerca de las playas del oc\u00e9ano.<br \/>\nA menos de 1 km de la playa de Mauret, a 2,5 km del centro de la ciudad y a un paso del mercado cubierto, encontrar\u00e1s tiendas al final de la calle, as\u00ed como el carril bici.<br \/>\nTiene capacidad para 8 personas; cuenta con 4 dormitorios, 2 cuartos de ba\u00f1o, 2 aseos, una cocina abierta muy bien equipada, un sal\u00f3n y un comedor.<br \/>\nAll\u00ed encontrar\u00e1s conexi\u00f3n de fibra \u00f3ptica, barbacoa, plancha, cuna y trona, muebles de jard\u00edn, tumbonas, juegos al aire libre, posibilidad de alquilar ropa de cama, aparcamiento y bicicletas a tu disposici\u00f3n.<\/p>","protected":false},"featured_media":248906,"template":"","villeh":[2170],"type-hebergement":[2184],"class_list":["post-116517","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d.jpg",600,337,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-cd24ef776212743b434743212d53d60d-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Jolie maison de 100m\u00b2, de plein pied enti\u00e8rement r\u00e9nov\u00e9e, 3 \u00e9toiles avec un jardin cl\u00f4tur\u00e9 et arbor\u00e9 de 750 m\u00b2. Elle est situ\u00e9e au Nord du Bassin dans la commune [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116517\/revisions"}],"predecessor-version":[{"id":223914,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/116517\/revisions\/223914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/248906"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=116517"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=116517"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=116517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}