{"id":59674,"date":"2006-08-30T12:51:49","date_gmt":"2006-08-30T10:51:49","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/hotel-la-villa-du-cap\/"},"modified":"2026-09-02T03:05:37","modified_gmt":"2026-09-02T01:05:37","slug":"hotel-la-villa-du-cap","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/hotel-la-villa-du-cap\/","title":{"rendered":"Hotel La Villa du Cap"},"content":{"rendered":"<p>La Villa du Cap est\u00e1 situada en el pueblo de Canon. Dispone de 10 habitaciones, algunas en la planta baja y otras en el primer piso. Las playas del pueblo y la zona ostr\u00edcola con sus caba\u00f1as de madera est\u00e1n muy cerca, s\u00f3lo hay que cruzar la carretera. La playa de Truc Vert est\u00e1 a pocos kil\u00f3metros. En la parte trasera del hotel hay un jard\u00edn-terraza donde podr\u00e1 tomar algo despu\u00e9s de un d\u00eda en el mar, en barco o en bicicleta.<\/p>","protected":false},"featured_media":218937,"template":"","villeh":[2166],"type-hebergement":[2183],"class_list":["post-59674","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-hotels"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-17400d7c4561077c84e2e1ba1e203448-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019h\u00f4tel \u00ab\u00a0La Villa du Cap\u00a0\u00bb est situ\u00e9 dans le village du Canon. Il dispose de 10 chambres, certaines au rez de chauss\u00e9e, d&rsquo;autres au premier \u00e9tage. Les plages du village, [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59674\/revisions"}],"predecessor-version":[{"id":192874,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59674\/revisions\/192874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/218937"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=59674"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=59674"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=59674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}