{"id":59683,"date":"2009-04-03T11:46:52","date_gmt":"2009-04-03T09:46:52","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/hotel-ttiki-etchea\/"},"modified":"2026-09-02T03:05:45","modified_gmt":"2026-09-02T01:05:45","slug":"hotel-ttiki-etchea","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/hotel-ttiki-etchea\/","title":{"rendered":"Hotel Ttiki Etchea"},"content":{"rendered":"<p>Situado a orillas del oc\u00e9ano y con acceso directo a la playa, el hotel Ttiki Etchea le da la bienvenida a Pyla-sur-Mer durante la temporada estival. Su nombre evoca su arquitectura vasca: una casa alta con entramado de madera y contraventanas verdes, rodeada por un jard\u00edn sombreado por pinos, que se puede disfrutar desde la terraza.<br \/>\nEl hotel Ttiki Etchea cuenta con 27 habitaciones. Disfrute de la calma y la serenidad del lugar, un sitio excepcional: acceso directo a la playa, cerca de la duna de Pilat, del Banc d'Arguin y de la isla de los P\u00e1jaros, que puede descubrir en excursiones en barco.<\/p>","protected":false},"featured_media":267539,"template":"","villeh":[2165],"type-hebergement":[2183],"class_list":["post-59683","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-la-teste-de-buch","type-hebergement-hotels"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c.bmp",753,500,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c-600x398.jpg",600,398,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c.bmp",753,500,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c.bmp",753,500,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c.bmp",753,500,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c.bmp",753,500,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/07\/sirtaqui-a18f174ca98620d371262e13985d1b1c-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Situ\u00e9 au bord de l\u2019oc\u00e9an avec acc\u00e8s direct \u00e0 la plage, l\u2019h\u00f4tel Ttiki Etchea vous accueille \u00e0 Pyla sur Mer \u00e0 la belle saison. Son nom \u00e9voque son architecture basque [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59683\/revisions"}],"predecessor-version":[{"id":61013,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59683\/revisions\/61013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/267539"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=59683"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=59683"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=59683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}