{"id":59703,"date":"2008-05-26T11:56:08","date_gmt":"2008-05-26T09:56:08","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/centre-de-mer\/"},"modified":"2026-09-02T03:28:10","modified_gmt":"2026-09-02T01:28:10","slug":"centro-maritimo","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/centre-de-mer\/","title":{"rendered":"Centro del Mar"},"content":{"rendered":"<p>Centro de educaci\u00f3n para el desarrollo sostenible CE2D<\/p>\n<p>Situado en Andernos les Bains, en el coraz\u00f3n del Bassin de Arcachon, el Centro Mar y EDD (Educaci\u00f3n para el Desarrollo Sostenible) ofrece a los estudiantes un encuentro concreto y directo con este territorio, identificado como sitio Natura 2000 y Parque Natural Marino (desde junio de 2014) por la riqueza y singularidad de su patrimonio natural, paisaj\u00edstico y cultural\u2026.<\/p>\n<p>El Centro Mar y EDD acoge a estudiantes de los ciclos 1 a 4 y a sus profesores para estancias cortas, clases de descubrimiento e intervenciones puntuales, especialmente en el marco de excursiones de un d\u00eda.<\/p>\n<p>Creado por PEP 33, asociaci\u00f3n socia de la escuela p\u00fablica, el Centre de Mer tiene el proyecto y la vocaci\u00f3n de sensibilizar a los alumnos sobre el medio ambiente y el desarrollo sostenible, transmitirles un enfoque y hacerles experimentar con las diferentes nociones del medio ambiente.<\/p>","protected":false},"featured_media":239150,"template":"","villeh":[2170],"type-hebergement":[2186],"class_list":["post-59703","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-villages-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-1f978e886c56fbd389e11f3855ccab09-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"CE2D centre d\u2019\u00e9ducation au d\u00e9veloppement durable Situ\u00e9 \u00e0 Andernos les Bains au c\u0153ur du Bassin d\u2019Arcachon, le Centre de Mer et d\u2019E.D.D. (Education au D\u00e9veloppement Durable) fait vivre aux \u00e9l\u00e8ves [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59703\/revisions"}],"predecessor-version":[{"id":61030,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/59703\/revisions\/61030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/239150"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=59703"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=59703"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=59703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}