{"id":60131,"date":"2005-06-29T00:00:00","date_gmt":"2005-06-28T22:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/camping-les-ecureuils\/"},"modified":"2026-09-02T04:00:07","modified_gmt":"2026-09-02T02:00:07","slug":"camping-de-las-ardillas","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/camping-les-ecureuils\/","title":{"rendered":"Camping Les Ecureuils"},"content":{"rendered":"<p>El Camping Les \u00c9cureuils le da la bienvenida a Ar\u00e8s, en la bah\u00eda de Arcachon, en un entorno tranquilo y verde, ideal para unas vacaciones relajantes. Con sus 30 parcelas dedicadas exclusivamente a alquileres confortables, nuestro camping familiar es ideal para parejas y familias que buscan tranquilidad y buen ambiente.<br \/>\nEn las cercan\u00edas, podr\u00e1 descubrir las atracciones imprescindibles de la bah\u00eda de Arcachon: la Duna de Pilat, Cap Ferret, pueblos ostr\u00edcolas y sus catas, as\u00ed como magn\u00edficas playas. Los amantes de la naturaleza apreciar\u00e1n los numerosos paseos por el bosque y las ciclov\u00edas de los alrededores.<br \/>\nUn entorno revitalizante. Venga a descubrir el encanto y la tranquilidad del camping, donde Charlotte y Quentin estar\u00e1n encantados de recibirle.<\/p>","protected":false},"featured_media":247100,"template":"","villeh":[2163],"type-hebergement":[2180],"class_list":["post-60131","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-ares","type-hebergement-campings"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457.jpg",1024,768,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457.jpg",1024,768,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457.jpg",1024,768,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457.jpg",1024,768,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-0b37f07c7b1c8053e84b2a2dbea8e457-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Camping Les \u00c9cureuils vous accueille \u00e0 Ar\u00e8s, sur le bassin d&rsquo;Arcachon, dans un cadre calme et verdoyant, parfait pour des vacances reposantes. Avec ses 30 emplacements exclusivement d\u00e9di\u00e9s \u00e0 [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":5,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60131\/revisions"}],"predecessor-version":[{"id":160003,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60131\/revisions\/160003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/247100"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=60131"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=60131"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=60131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}