{"id":60156,"date":"2005-06-29T00:00:00","date_gmt":"2005-06-28T22:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/camping-le-coq-hardi\/"},"modified":"2026-09-02T04:00:30","modified_gmt":"2026-09-02T02:00:30","slug":"el-camping-del-gallo-resistente","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/es\/hebergement\/camping-le-coq-hardi\/","title":{"rendered":"Camping Le Coq Hardi \u2013 Olas del oc\u00e9ano"},"content":{"rendered":"<p>El Camping Le Coq Hardi es el punto de partida ideal para explorar las maravillas de Bassin d'Arcachon. Durante sus vacaciones, podr\u00e1 descubrir los alrededores, incluida la famosa Dune du Pilat, Cap Ferret y los vi\u00f1edos de M\u00e9doc. Ya sea amante de la naturaleza, de los deportes n\u00e1uticos o simplemente en busca de tranquilidad, este destino le ofrece el marco perfecto para recargar las pilas mientras explora los tesoros de la regi\u00f3n.<\/p>\n<p>Adem\u00e1s de su ubicaci\u00f3n privilegiada con acceso directo a la playa, el camping ofrece un rico programa de animaci\u00f3n y actividades para toda la familia. Aproveche las diversas instalaciones, desde piscinas y toboganes hasta campos deportivos y zonas de juego, para pasar unas vacaciones din\u00e1micas e inolvidables.<\/p>","protected":false},"featured_media":251543,"template":"","villeh":[2164],"type-hebergement":[2180],"class_list":["post-60156","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-campings"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213-150x150.png",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213.png",500,500,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-4e64c28d2015011b2c7616510b4bb213-12x12.png",12,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Camping Le Coq Hardi est le point de d\u00e9part id\u00e9al pour explorer les merveilles du Bassin d&rsquo;Arcachon. Pendant vos vacances, vous pourrez d\u00e9couvrir les environs tels que la c\u00e9l\u00e8bre [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":3,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60156\/revisions"}],"predecessor-version":[{"id":166963,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/hebergement\/60156\/revisions\/166963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media\/251543"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/media?parent=60156"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/villeh?post=60156"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/es\/wp-json\/wp\/v2\/type-hebergement?post=60156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}