{"id":112982,"date":"2005-11-08T00:00:00","date_gmt":"2005-11-07T23:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/monsieur-jean-marc-bordessoule-2\/"},"modified":"2026-09-02T03:30:04","modified_gmt":"2026-09-02T01:30:04","slug":"jean-marc-bordessoule-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/monsieur-jean-marc-bordessoule-2\/","title":{"rendered":"Signor Jean-Marc BORDESSOULE"},"content":{"rendered":"<p>Atmosfera delle case di pescatori sul porto dell&#039;Aiguillon, ville balneari del XIX secolo nella Citt\u00e0 d&#039;Inverno, bagni in famiglia lungo le spiagge o crociera scoperta sulla Bassin con partenza dal molo, i quartieri di Arcachon presentano una bella diversit\u00e0 architettonica e culturale. Questa citt\u00e0 vivace tutto l&#039;anno \u00e8 un luogo di vacanza esotico e unico, circondato da notevoli spazi naturali. \u00c8 il dolce suono dello sciabordio delle barche che ti culla da questo appartamento. Apprezzerai la sua posizione privilegiata sul porto turistico di Arcachon, a cui si aggiunge la comodit\u00e0 di una terrazza e di un parcheggio.<\/p>","protected":false},"featured_media":0,"template":"","villeh":[2167],"type-hebergement":[2184],"class_list":["post-112982","hebergement","type-hebergement","status-publish","hentry","villeh-arcachon","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Ambiance maisons de p\u00eacheurs sur le port de l\u2019Aiguillon, villas \u00e9poque bains de mer du XIX\u00e8me dans la Ville d\u2019Hiver, baignade familiale le long des plages, ou croisi\u00e8re d\u00e9couverte du [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/112982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/112982\/revisions"}],"predecessor-version":[{"id":113365,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/112982\/revisions\/113365"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=112982"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=112982"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=112982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}