{"id":113045,"date":"2005-11-08T00:00:00","date_gmt":"2005-11-07T23:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/monsieur-andre-gourdon-3\/"},"modified":"2026-09-02T03:30:12","modified_gmt":"2026-09-02T01:30:12","slug":"il-signor-andre-gourdon-3","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/monsieur-andre-gourdon-3\/","title":{"rendered":"Signor Andr\u00e9 GOURDON"},"content":{"rendered":"<p>\u201cBenvenuti in un noleggio targato \u201cNaturalmente Bassin\u201d: il senso di accoglienza e i valori che coinvolgono i nostri professionisti! \u00bb Appartamento T2 di 50 m\u00b2 al piano superiore, situato a Cap Ferret, a 700 m dalla spiaggia dell&#039;oceano Horizon, a 100 m dalle spiagge del bacino di Arcachon e a 50 m dal centro citt\u00e0. Con una camera da letto e un divano letto, l&#039;alloggio pu\u00f2 ospitare 4 persone. La terrazza permette di consumare tutti i pasti all&#039;aperto e godersi cos\u00ec le lunghe giornate e serate estive.<br \/>\nAffitto settimanale, quindicinale o mensile.<br \/>\nBenvenuto dal proprietario.<\/p>","protected":false},"featured_media":260866,"template":"","villeh":[2166],"type-hebergement":[2184],"class_list":["post-113045","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5.jpg",1200,800,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5-768x512.jpg",768,512,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5.jpg",1200,800,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5.jpg",1200,800,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-a923fbe6d786f541511acbdd29da4fc5-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00ab Bienvenue dans une location labellis\u00e9e \u00ab Naturellement Bassin \u00bb : le sens de l\u2019accueil et des valeurs qui engagent nos professionnels ! \u00bb Appartement T2 de 50 m\u00b2 \u00e0 [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113045\/revisions"}],"predecessor-version":[{"id":113370,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113045\/revisions\/113370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/260866"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=113045"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=113045"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=113045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}