{"id":113545,"date":"2009-05-20T11:11:39","date_gmt":"2009-05-20T09:11:39","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/cap-sittelle-2\/"},"modified":"2026-09-02T03:30:52","modified_gmt":"2026-09-02T01:30:52","slug":"capo-sittella-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/cap-sittelle-2\/","title":{"rendered":"Capo picchio muratore"},"content":{"rendered":"<p>Dopo una carriera professionale trascorsa in una grande citt\u00e0 e giunti all\u2019et\u00e0 della pensione, ai proprietari di Cap Sittelle \u00e8 venuta spontanea un\u2019idea: tornare nella casa di famiglia al Cap Ferret e creare l\u00ec un ambiente che permettesse ad altri di staccare la spina dalla routine quotidiana. Qui tutto \u00e8 raggiungibile a piedi o in bicicletta, il che facilita i primi passi: respirare a pieni polmoni, lasciare l\u2019auto a casa! L\u2019appartamento per gli ospiti al primo piano della casa \u00e8 spazioso, indipendente, con una terrazza all\u2019ombra dei pini e una cucina a disposizione.<br \/>\nPer il resto, ci pensano i proprietari della casa. La colazione viene lasciata davanti all\u2019appartamento ogni giorno. La padrona di casa ama l\u2019arte e organizza numerose mostre. All\u2019ora dell\u2019inaugurazione, siete invitati a condividere un momento in cui si parla di arte e degli angoli segreti della Presqu\u2019\u00eele.<\/p>","protected":false},"featured_media":219586,"template":"","villeh":[2166],"type-hebergement":[2181],"class_list":["post-113545","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-chambres-dhotes"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-3a142648c1e34866cb8013bc7cffa465-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Apr\u00e8s une carri\u00e8re professionnelle dans une tr\u00e8s grande ville et \u00e0 l\u2019\u00e2ge de la retraite, une \u00e9vidence s\u2019est naturellement impos\u00e9e aux propri\u00e9taires de Cap Sittelle. Revenir dans la maison familiale [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113545\/revisions"}],"predecessor-version":[{"id":115401,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113545\/revisions\/115401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/219586"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=113545"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=113545"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=113545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}