{"id":113747,"date":"2013-02-14T17:30:38","date_gmt":"2013-02-14T16:30:38","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/cote-bassin-2\/"},"modified":"2026-09-02T03:31:11","modified_gmt":"2026-09-02T01:31:11","slug":"cote-bassin-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/cote-bassin-2\/","title":{"rendered":"Lato Bassin"},"content":{"rendered":"<p>Incantevole casa con una camera da letto per 2 persone. TV. Situato ai margini della Bassin di Arcachon, in una propriet\u00e0 molto tranquilla e boscosa, a sua volta situata in un ambiente selvaggio e naturale, \u00e8 apprezzato per il suo lato molto accogliente e caldo.<\/p>\n<p>Dotata di giardino con terrazza attrezzata con mobili e 2 sdraio in teak, con il sentiero costiero sul retro della propriet\u00e0. Parcheggio nascosto all&#039;interno della propriet\u00e0. <\/p>","protected":false},"featured_media":227940,"template":"","villeh":[2168],"type-hebergement":[2184],"class_list":["post-113747","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936.jpg",900,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936-768x512.jpg",768,512,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936.jpg",900,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936.jpg",900,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936.jpg",900,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-a5ce65ae44529710a1f88c9348a17936-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Maison de Charme avec une chambre pour 2 pers. TV. Situ\u00e9e au bord du Bassin d&rsquo;Arcachon, dans une propri\u00e9t\u00e9 tr\u00e8s tranquille et arbor\u00e9e, elle m\u00eame situ\u00e9e dans un cadre sauvage [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113747\/revisions"}],"predecessor-version":[{"id":115422,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/113747\/revisions\/115422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/227940"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=113747"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=113747"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=113747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}