{"id":114620,"date":"2017-08-02T17:18:49","date_gmt":"2017-08-02T15:18:49","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/la-clairiere-2\/"},"modified":"2026-09-02T03:32:19","modified_gmt":"2026-09-02T01:32:19","slug":"la-radura-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/la-clairiere-2\/","title":{"rendered":"Il pascolo"},"content":{"rendered":"<p>A 1,5 km dal Lago di Cazaux, soggiornate nella nostra casa nuova climatizzata di 140 m\u00b2, su un unico piano, con piscina semi-interrata di forma ottagonale allungata 6 m x 4 m, profondit\u00e0 1,31 m, riscaldata, a disposizione da aprile a ottobre a seconda delle condizioni meteorologiche. La casa si trova in un tranquillo complesso residenziale, vicino alla pista ciclabile che collega il lago e l'oceano, e dispone di un giardino recintato e protetto di 1290 m\u00b2 con un'ampia terrazza in legno di 170 m\u00b2 e un campo da bocce. Ampio soggiorno molto luminoso che si affaccia sulla terrazza con tenda da sole, cucina attrezzata, zona pranzo e salotto, quattro camere da letto di cui tre dotate di 1 letto da 160\u00d7200 cm e una dotata di 2 letti da 90\u00d7190 cm (TV in ogni camera). Le camere dotate di letti matrimoniali dispongono di bagno privato con doccia a filo pavimento. Un bagno indipendente con vasca e 2 WC separati.<br \/>\nNumero di registrazione: 33529000248CB<\/p>","protected":false},"featured_media":255246,"template":"","villeh":[2165],"type-hebergement":[2184],"class_list":["post-114620","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-la-teste-de-buch","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03.jpg",1152,768,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03-768x512.jpg",768,512,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03.jpg",1152,768,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03.jpg",1152,768,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/05\/sirtaqui-faa3926be8c11a215cdce37e3280ac03-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A 1,5 km du Lac de Cazaux, s\u00e9journez dans notre maison neuve climatis\u00e9e de 140 m2, de plain pied, avec piscine semi-enterr\u00e9e type octogonale allong\u00e9e 6mx4m profondeur 1.31m, chauff\u00e9e, \u00e0 [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/114620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":4,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/114620\/revisions"}],"predecessor-version":[{"id":254449,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/114620\/revisions\/254449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/255246"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=114620"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=114620"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=114620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}