{"id":115376,"date":"2020-02-03T15:41:33","date_gmt":"2020-02-03T14:41:33","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/village-du-falgouet-chalet-oyat-6-8-personnes-2\/"},"modified":"2026-09-02T03:33:58","modified_gmt":"2026-09-02T01:33:58","slug":"villaggio-di-falgouet-chalet-oyat-6-8-persone-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/village-du-falgouet-chalet-oyat-6-8-personnes-2\/","title":{"rendered":"Villaggio di Falgou\u00ebt \u2013 Chalet Oyat 6\/8 persone"},"content":{"rendered":"<p>Chalet Oyat 6\/8 persone di 68 m\u00b2 certificato Ecolabel Europeo Turismo e Disabilit\u00e0 nel 2019.<br \/>\nLe Falgou\u00ebt \u00e8 un villaggio eco-sostenibile che ricorda le capanne dei pescatori, situato in un sito eccezionale ai margini di Arcachon Bassin con accesso diretto alla spiaggia.<br \/>\nGli otto chalet si fondono perfettamente con l&#039;ambiente circostante. Un giardino curato, che si fonde con la flora locale, impreziosisce gli chalet e guida i vacanzieri verso la spiaggia.<br \/>\nIl sito \u00e8 aperto a tutti. Accoglie anche piccoli gruppi che possono utilizzare una sala polivalente alle condizioni stabilite dall&#039;associazione.<br \/>\nGli chalet sono completamente arredati e dotati di elettrodomestici.<br \/>\nAperto tutto l&#039;anno. Si accettano buoni vacanza ANCV.<br \/>\nLa passeggiata pedonale in fondo al giardino conduce gli utenti di Falgou\u00ebt al porto turistico e ai porti pescherecci, ai negozi e alle attivit\u00e0 locali.<\/p>","protected":false},"featured_media":260708,"template":"","villeh":[2170],"type-hebergement":[2184],"class_list":["post-115376","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-705dd79235aea9b13b39bbfdcccf745e-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Chalet Oyat 6\/8 personnes de 68 m\u00b2 labellis\u00e9 Ecolabel Europ\u00e9en Tourisme et Handicap en 2019. Le Falgou\u00ebt est un village \u00e9co-solidaire aux allures de cabanes de p\u00eacheurs, implant\u00e9 sur un [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115376\/revisions"}],"predecessor-version":[{"id":115557,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115376\/revisions\/115557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/260708"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=115376"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=115376"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=115376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}