{"id":115658,"date":"2020-06-12T16:46:46","date_gmt":"2020-06-12T14:46:46","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/chez-bella-cote-bassin-chambres-dhotes-2\/"},"modified":"2026-09-02T03:34:04","modified_gmt":"2026-09-02T01:34:04","slug":"presso-bella-cote-bassin-camere-per-ospiti-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/chez-bella-cote-bassin-chambres-dhotes-2\/","title":{"rendered":"A Bella C\u00f4t\u00e9 Bassin \u2013 Bed and Breakfast"},"content":{"rendered":"<p>Relax garantito!<br \/>\n\u2013 Affitta due camere doppie<br \/>\n\u2013 Una suite (per 4 persone) con bagno privato. Si affacciano su una graziosa terrazza in teak e su un giardino alberato.<br \/>\nArredate con gusto, ispirate al tema del mare, dispongono di bagno privato e di un ingresso indipendente che d\u00e0 sul giardino.<br \/>\nSarete immersi nella tranquillit\u00e0, senza alcun rumore fastidioso se non il canto degli uccelli!<br \/>\nLe camere si trovano in una dependance in legno in stile arcachonese, separata dalla casa principale. Posizione ideale: la spiaggia dista 5 km, il porto di Larros \u00e8 raggiungibile a piedi in pochi minuti, con capanne per ostriche e ristoranti.<br \/>\nLa pista ciclabile passa davanti a casa.<br \/>\nPotrete parcheggiare gratuitamente davanti alla propriet\u00e0.<br \/>\nBiancheria da letto e da bagno inclusa.<br \/>\nLa casa principale e la dependance sono disponibili per 10 persone (5 camere da letto, 3 bagni) e vengono affittate arredate da luglio a settembre.<\/p>","protected":false},"featured_media":228110,"template":"","villeh":[2168],"type-hebergement":[2181],"class_list":["post-115658","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-gujan-mestras","type-hebergement-chambres-dhotes"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5.jpg",1200,900,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5-1024x768.jpg",1024,768,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5.jpg",1200,900,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5.jpg",1200,900,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-d91577042f114af9fbac104d4a28b5b5-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"D\u00e9tente assur\u00e9e ! &#8211; Loue deux chambres doubles &#8211; Une suite (pour 4 pers) avec salle de bain privative. Elles s\u2019ouvrent sur une jolie terrasse en teck et un jardin [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115658\/revisions"}],"predecessor-version":[{"id":194143,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/115658\/revisions\/194143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/228110"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=115658"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=115658"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=115658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}