{"id":59926,"date":"2018-05-11T14:25:04","date_gmt":"2018-05-11T12:25:04","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/locaplage-20-studio-galip-plain-pied\/"},"modified":"2026-09-02T03:32:44","modified_gmt":"2026-09-02T01:32:44","slug":"locaplage-20-monolocale-galip-al-piano-terra","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/it\/hebergement\/locaplage-20-studio-galip-plain-pied\/","title":{"rendered":"Locaplage 20: monolocale \u201cGalip\u201d su un unico livello"},"content":{"rendered":"<p>Affitto vacanze situato tra Arcachon e L\u00e8ge Cap-Ferret e a 30 minuti da Bordeaux e dai suoi vigneti.<\/p>\n<p>Idealmente situato nel cuore dell&#039;Bassin di Arcachon, nel villaggio di Taussat nel comune di Lanton, potrete approfittare del vostro soggiorno, immersi nella natura, per esplorare l&#039;Bassin di Arcachon.<\/p>\n<p>Potrete scoprire liberamente i siti chiave dei comuni di Arcachon, La teste de Buch, Gujan-Mestras, le Teich, Biganos, Audenge, Andernos, Ar\u00e8s e L\u00e8ge Cap-Ferret, come la Dune du Pyla, il Faro di Cap- Furetto, ecc\u2026<\/p>\n<p>Puoi anche goderti le numerose passeggiate a piedi o in bicicletta, le escursioni offerte dall&#039;alloggio o nelle vicinanze.<\/p>","protected":false},"featured_media":220704,"template":"","villeh":[2164],"type-hebergement":[2184],"class_list":["post-59926","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-coeur-de-bassin","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-41f0133ee8bab9aa0844ef220c438884-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"dfuzionadmin","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Location de vacances situ\u00e9 entre Arcachon et L\u00e8ge Cap-Ferret et \u00e0 30 minutes de Bordeaux et de ses vignobles. Id\u00e9alement situ\u00e9 au Coeur du Bassin d&rsquo;Arcachon dans le village de [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/59926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/59926\/revisions"}],"predecessor-version":[{"id":61228,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/hebergement\/59926\/revisions\/61228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/220704"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=59926"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/villeh?post=59926"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/type-hebergement?post=59926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}