{"id":10547,"date":"2017-11-02T12:22:37","date_gmt":"2017-11-02T11:22:37","guid":{"rendered":"https:\/\/www.bassin-arcachon.com\/?p=10547"},"modified":"2023-11-22T16:07:30","modified_gmt":"2023-11-22T15:07:30","slug":"scopri-lestran-betey","status":"publish","type":"post","link":"https:\/\/bassin-arcachon.com\/it\/decouvrez-lestran-betey\/","title":{"rendered":"Scopri il litorale di Betey"},"content":{"rendered":"<h2>Ogni giorno sull&#039;Arcachon Bassin, l&#039;incanto della battigia si svela al ritmo dell&#039;acqua che scorre verso l&#039;oceano.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76.jpg 1500w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-76-1200x800.jpg 1200w\" alt=\"pesca-a-piedi-agenzia-SIBA-les-conteurs-76\" width=\"1500\" height=\"1000\" title=\"- - Bassin d&#039;Arcachon\"><br \/>\nPotremmo vivere qui quotidianamente, chi conosce davvero i piccoli abitanti che si nascondono nella sabbia e nel fango? Tutti conosciamo bivalvi come vongole, cozze e vongole, o crostacei come granchi e gamberi, ma molti di questi animali che ci circondano ci rimangono totalmente sconosciuti.<\/p>\n<p><strong>Tuttavia, alcuni di loro svolgono un ruolo fondamentale per questo ecosistema, e talvolta anche per l&#039;uomo!<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-1024x683.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17-1200x800.jpg 1200w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-17.jpg 1500w\" alt=\"pesca-a-piedi-agenzia-SIBA-les-conteurs-17\" width=\"1024\" height=\"683\" title=\"- - Bassin d&#039;Arcachon\"><\/p>\n<p>In alto sulla spiaggia si accumulano alghe e altri guinzagli marini. Questo \u00e8 il dominio dei Talitres... Cosa!? Niente di troppo complicato, sono le pulci di mare, questi piccoli crostacei che si nascondono sotto le alghe e saltano ovunque quando giri i mucchi. Sono l\u00ec per proteggersi, certo, ma anche per mangiarli, decomporli e integrarli nella sabbia, favorendo cos\u00ec lo sviluppo di praterie salate e cordoni dunali. Non per niente i giardinieri raccolgono questi scarti marini per i propri giardini.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-1024x683.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24-1200x800.jpg 1200w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-24.jpg 1500w\" alt=\"pesca-a-piedi-agenzia-SIBA-les-conteurs-24\" width=\"1024\" height=\"683\" title=\"- - Bassin d&#039;Arcachon\"><\/p>\n<p>Hai mai osservato questi piccoli colpi di scena a volte numerosi sulle spiagge sabbiose? Questi sono gli escrementi dell&#039;Arenicola... ma state tranquilli, sono puliti. L&#039;Arenicola \u00e8 un verme marino che si seppellisce nella sabbia in un buco a forma di &quot;U&quot;. Si nutre del fango che vi si accumula. \u00c8 usato come esca per la pesca con l&#039;amo. In laboratorio riusciamo persino a fargli produrre sangue umano! Avresti mai immaginato che un verme potesse salvarti la vita?<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-1024x683.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64-1200x800.jpg 1200w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-64.jpg 1500w\" alt=\"- - Bassin d&#039;Arcachon\" width=\"1024\" height=\"683\" title=\"- - Bassin d&#039;Arcachon\"><\/p>\n<p>Sulle nostre spiagge sono presenti numerosi gasteropodi come la pervinca comune. Ma pensiamo un pensierino alle Hydrobies, minuscole lumache marine di appena 3mm che ripuliscono le piante dalle praterie salate dalle alghe che le possono ricoprire.<\/p>\n<blockquote>\n<h4>Questo fossile vivente \u00e8 importantissimo per gli uccelli che se ne cibano, se ne contano pi\u00f9 di 10.000 per metro quadrato!<\/h4>\n<\/blockquote>\n<p>Il Ciclope \u00e8 un&#039;altra lumaca divertente. Se si trova accidentalmente sulla schiena, come un ginnasta user\u00e0 il suo unico piede per girarsi. Uno spazzino, si nutre di animali morti dalla battigia. Previene cos\u00ec la diffusione delle malattie e partecipa al mantenimento dell&#039;ecosistema.<\/p>\n<blockquote>\n<h4>Nonostante il suo piccolo centimetro di lunghezza, pu\u00f2 percepire la presenza di un cadavere a quasi 30 metri di distanza!<\/h4>\n<\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-1024x683.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70-1200x800.jpg 1200w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-70.jpg 1500w\" alt=\"pesca-a-piedi-agenzia-SIBA-les-conteurs-70\" width=\"1024\" height=\"683\" title=\"- - Bassin d&#039;Arcachon\"><\/p>\n<p>Tutti questi animali dipendono dalle nostre praterie di alghe, che attualmente sono particolarmente minacciate dall&#039;inquinamento. Quando peschi a piedi per piacere, cerca il pi\u00f9 possibile di non camminare sull&#039;erba marina per preservare a lungo il nostro bellissimo Bassin di Arcachon.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-1024x683.jpg\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" srcset=\"https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-1024x683.jpg 1024w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-450x300.jpg 450w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-768x512.jpg 768w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-640x427.jpg 640w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13-1200x800.jpg 1200w, https:\/\/www.bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-13.jpg 1500w\" alt=\"- - Bassin d&#039;Arcachon\" width=\"1024\" height=\"683\" title=\"- - Bassin d&#039;Arcachon\"><\/p>\n<p>Per vivere altre avventure con Alexandre per scoprire il Bassin di Arcachon, contatta <a href=\"http:\/\/www.ares-tourisme.com\/\" target=\"_blank\" rel=\"noopener\">Ufficio del Turismo di Ar\u00e8s.<\/a><\/p>\n<p>Scoprire <a href=\"https:\/\/baliste.jimdofree.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">la fauna e la flora marina del Bassin di Arcachon<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ogni giorno sulla Bassin di Arcachon, l&#039;incanto del litorale si svela al ritmo dell&#039;acqua che fugge verso l&#039;oceano<\/p>","protected":false},"author":16,"featured_media":10548,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[2133,2129],"tags":[186,76,238,242,98,236],"class_list":["post-10547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-nature-art-de-vivre","tag-automne","tag-bassin-darcachon","tag-betey","tag-hiver","tag-peche","tag-peche-a-pied"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325.jpg",1000,667,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325-768x512.jpg",768,512,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325.jpg",1000,667,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325.jpg",1000,667,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325.jpg",1000,667,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2017\/11\/peche-a-pieds-SIBA-agence-les-conteurs-77-e1548078346325-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Alexandre, Guide touristique \u00e0 Ar\u00e8s","author_link":"https:\/\/bassin-arcachon.com\/it\/author\/alexsibaares\/"},"uagb_comment_info":0,"uagb_excerpt":"Chaque jour sur le Bassin d\u2019Arcachon, la f\u00e9erie de l\u2019estran se d\u00e9voile au rythme de l\u2019eau qui s\u2019enfuit vers l\u2019oc\u00e9an","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/posts\/10547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/comments?post=10547"}],"version-history":[{"count":0,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/posts\/10547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media\/10548"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/media?parent=10547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/categories?post=10547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/it\/wp-json\/wp\/v2\/tags?post=10547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}