{"id":216536,"date":"2009-10-23T15:16:36","date_gmt":"2009-10-23T13:16:36","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/les-ernestines\/"},"modified":"2026-09-02T03:30:55","modified_gmt":"2026-09-02T01:30:55","slug":"%d1%8d%d1%80%d0%bd%d0%b5%d1%81%d1%82%d0%b8%d0%bd%d1%86%d1%8b","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/ru\/hebergement\/les-ernestines\/","title":{"rendered":"Les Ernestines"},"content":{"rendered":"<p>A quelques minutes \u00e0 pied des plages, du centre-ville et du port de plaisance, \u00e0 proximit\u00e9 imm\u00e9diate d&rsquo;une piste cyclable, nous vous proposons notre vaste maison de 120m2, enti\u00e8rement r\u00e9nov\u00e9e en 2024. Entour\u00e9 d&rsquo;un jardin clos et arbor\u00e9, \u00e9quip\u00e9 d&rsquo;un barbecue et d&rsquo;une grande terrasse en bois ce lieu situ\u00e9 dans un quartier r\u00e9sidentiel \u00e0 la fois calme et proche de toutes commodit\u00e9s, vous invite \u00e0 passer un s\u00e9jour reposant en famille ou entre amis. Id\u00e9alement con\u00e7ue pour accueillir 6 \u00e0 8 personnes, la maison offre 4 chambres, 2 salles de bain, 2 WC s\u00e9par\u00e9s, une buanderie et un grand salon\/salle \u00e0 manger avec sa cuisine ind\u00e9pendante. Salon de jardin, hamacs et chaises longues compl\u00e8tent l&rsquo;\u00e9quipement. <\/p>","protected":false},"featured_media":248541,"template":"","villeh":[2170],"type-hebergement":[2184],"class_list":["post-216536","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-andernos-les-bains","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c.jpg",816,684,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c-600x503.jpg",600,503,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c-768x644.jpg",768,644,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c.jpg",816,684,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c.jpg",816,684,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c.jpg",816,684,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/04\/sirtaqui-eb5d46465295fae8d4c42d8fcc912b5c-14x12.jpg",14,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/ru\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A quelques minutes \u00e0 pied des plages, du centre-ville et du port de plaisance, \u00e0 proximit\u00e9 imm\u00e9diate d&rsquo;une piste cyclable, nous vous proposons notre vaste maison de 120m2, enti\u00e8rement r\u00e9nov\u00e9e [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/hebergement\/216536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":2,"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/hebergement\/216536\/revisions"}],"predecessor-version":[{"id":231762,"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/hebergement\/216536\/revisions\/231762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/media\/248541"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/media?parent=216536"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/villeh?post=216536"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/ru\/wp-json\/wp\/v2\/type-hebergement?post=216536"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}