{"id":113225,"date":"2005-11-08T00:00:00","date_gmt":"2005-11-07T23:00:00","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/madame-dominique-bennevault-2\/"},"modified":"2026-09-02T03:30:32","modified_gmt":"2026-09-02T01:30:32","slug":"dominique-bennevault-%e5%a5%b3%e5%a3%ab-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/zh\/hebergement\/madame-dominique-bennevault-2\/","title":{"rendered":"\u591a\u7c73\u5c3c\u514b\u00b7\u8d1d\u5185\u6c83\u7279\u592b\u4eba"},"content":{"rendered":"<p>\u542b\u505c\u8f66\u3002\u60a8\u6b65\u884c\u6216\u9a91\u81ea\u884c\u8f66\u51fa\u884c\uff08\u901a\u8fc7\u79df\u8d41\u516c\u53f8\uff09\uff1b\u81ea\u884c\u8f66\u9053\u8ddd\u79bb\u8fd9\u91cc100\u7c73\u3002\u9644\u8fd1\u6709\u5546\u5e97\u548c\u670d\u52a1\u8bbe\u65bd\u3002\u8fd9\u95f4\u516c\u5bd3\u6700\u597d\u7684\u5730\u65b9\uff1a\u4f4d\u7f6e\u3001\u4eae\u5ea6\u3001\u671d\u5357\u7684\u9633\u53f0\u3001\u53ef\u9006\u7a7a\u8c03\u3002\u4f4f\u5bbf\u6700\u8fd1\u88ab Gironde Tourisme \u8bc4\u4e3a 3 \u661f\u7ea7\u3002<\/p>","protected":false},"featured_media":262000,"template":"","villeh":[2167],"type-hebergement":[2184],"class_list":["post-113225","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-arcachon","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9.jpg",800,533,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9-600x400.jpg",600,400,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9-768x512.jpg",768,512,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9.jpg",800,533,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9.jpg",800,533,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9.jpg",800,533,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/06\/sirtaqui-48a740540f80b89a0c72e201399fd7d9-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/zh\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Parking inclus. Vos d\u00e9placements se font \u00e0 pieds ou \u00e0 v\u00e9lo (via loueur) ; la piste cyclable passe \u00e0 100 m\u00e8tres. Les commerces et services sont \u00e0 proximit\u00e9. Le plus [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/113225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/113225\/revisions"}],"predecessor-version":[{"id":113389,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/113225\/revisions\/113389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media\/262000"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media?parent=113225"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/villeh?post=113225"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/type-hebergement?post=113225"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}