{"id":114673,"date":"2017-11-13T12:32:55","date_gmt":"2017-11-13T11:32:55","guid":{"rendered":"https:\/\/bassin-arcachon.com\/hebergement\/madame-josette-pallas-2\/"},"modified":"2026-09-02T03:32:24","modified_gmt":"2026-09-02T01:32:24","slug":"%e4%b9%94%e5%a1%9e%e7%89%b9%c2%b7%e5%b8%95%e6%8b%89%e6%96%af%e5%a4%ab%e4%ba%ba-2","status":"publish","type":"hebergement","link":"https:\/\/bassin-arcachon.com\/zh\/hebergement\/madame-josette-pallas-2\/","title":{"rendered":"\u4e54\u8d5b\u7279\u00b7\u5e15\u62c9\u65af\u5973\u58eb"},"content":{"rendered":"<p>105 \u5e73\u65b9\u7c73\u7684\u516c\u5bd3\u4f4d\u4e8e Cap Ferret\uff0c\u9760\u8fd1\u6d77\u6ee9\u548c\u5e02\u4e2d\u5fc3\u3002\u8be5\u4f4f\u5bbf\u62e5\u6709 3 \u95f4\u5367\u5ba4\uff0c\u53ef\u5bb9\u7eb3 6 \u4eba\uff0c\u8ddd\u79bb Bassin \u548c\u590f\u5b63\u65e5\u5e38\u5e02\u573a\u4ec5\u51e0\u6b65\u4e4b\u9065\uff0c\u60a8\u53ef\u4ee5\u5728\u90a3\u91cc\u8d2d\u4e70\u65b0\u9c9c\u7684\u5f53\u5730\u4ea7\u54c1\u3002\u6bcf\u5468\u3001\u6bcf\u4e24\u5468\u51fa\u79df\u3002<br \/>\n\u53d7\u5230\u4e1a\u4e3b\u7684\u6b22\u8fce\u3002<\/p>","protected":false},"featured_media":220513,"template":"","villeh":[2166],"type-hebergement":[2184],"class_list":["post-114673","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","villeh-lege-cap-ferret","type-hebergement-locations-de-vacances"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5.jpg",800,600,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5-600x450.jpg",600,450,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5-768x576.jpg",768,576,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5.jpg",800,600,false],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5.jpg",800,600,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5.jpg",800,600,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/01\/sirtaqui-53a9f7eb00aca6255fd1331e832329c5-16x12.jpg",16,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/zh\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Appartement de 105 m2 situ\u00e9 au Cap Ferret \u00e0 proximit\u00e9 des plages et du centre ville. Avec ces 3 chambres le logement peut accueillir 6 personnes et \u00e0 quelques pas [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/114673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/114673\/revisions"}],"predecessor-version":[{"id":115497,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/hebergement\/114673\/revisions\/115497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media\/220513"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media?parent=114673"}],"wp:term":[{"taxonomy":"villeh","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/villeh?post=114673"},{"taxonomy":"type-hebergement","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/type-hebergement?post=114673"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}