{"id":59730,"date":"2024-03-28T14:36:37","date_gmt":"2024-03-28T13:36:37","guid":{"rendered":"https:\/\/bassin-arcachon.com\/se-deplacer-sur-le-bassin\/locations-velo\/beach-bikes-2\/"},"modified":"2026-09-02T04:45:42","modified_gmt":"2026-09-02T02:45:42","slug":"%e6%b2%99%e6%bb%a9%e8%87%aa%e8%a1%8c%e8%bd%a62","status":"publish","type":"velo_cpt","link":"https:\/\/bassin-arcachon.com\/zh\/se-deplacer-sur-le-bassin\/locations-velo\/beach-bikes-2\/","title":{"rendered":"\u6c99\u6ee9\u8f66"},"content":{"rendered":"<p>\u8fd9\u5bb6\u81ea\u884c\u8f66\u79df\u8d41\u516c\u53f8\u5730\u7406\u4f4d\u7f6e\u4f18\u8d8a\uff0c\u8ddd\u79bb\u81ea\u884c\u8f66\u9053 2 \u5206\u949f\u8def\u7a0b\uff0c\u4f4d\u4e8e\u76f8\u5bf9\u5b89\u9759\u7684\u533a\u57df\uff0c\u975e\u5e38\u9002\u5408\u5e74\u8f7b\u7684\u9a91\u81ea\u884c\u8f66\u8005\u3002<br \/>\n\u4e58\u5750\u6211\u4eec\u7684\u84dd\u8272\u201c\u6cd5\u56fd\u5236\u9020\u201d\u81ea\u884c\u8f66\u4eab\u53d7\u8eab\u4e34\u5176\u5883\u7684\u9a91\u884c\u4f53\u9a8c\uff01\u7ecf\u5178\u81ea\u884c\u8f66\u3001\u7535\u52a8\u81ea\u884c\u8f66\u3001\u7535\u52a8\u8d27\u8239\u3001\u513f\u7ae5\u81ea\u884c\u8f66\u3001\u513f\u7ae5\u62d6\u8f66\u2026\u2026\u3002\u6211\u4eec\u4e3a\u5168\u5bb6\u4eba\u51c6\u5907\u4e86\u4e00\u4e9b\u4e1c\u897f\uff01<br \/>\n\u5c0f\u989d\u5916\uff1a<br \/>\n\u2013 \u5728\u7ebf\u9884\u8ba2\u5e76\u652f\u4ed8\u62bc\u91d1<br \/>\n\u2013 \u6bcf\u5468 7 \u5929\u5f00\u653e<br \/>\n\u2013 \u514d\u8d39\u9001\u8d27\u4e0a\u95e8\uff08\u53ef\u79df\u7528 2 \u8f86\u81ea\u884c\u8f66\u548c 2 \u5929\uff09<br \/>\n\u2013 \u6bcf\u5468 7 \u5929\u63d0\u4f9b\u7ef4\u4fee\u534f\u52a9<br \/>\n\u2013 \u9ad8\u7aef\u81ea\u884c\u8f66\u8f66\u961f\u3002<\/p>","protected":false},"featured_media":240475,"template":"","ville":[2155],"class_list":["post-59730","velo_cpt","type-velo_cpt","status-publish","has-post-thumbnail","hentry","ville-ares"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb.jpg",1200,798,false],"thumbnail":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb-150x150.jpg",150,150,true],"medium":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb-600x399.jpg",600,399,true],"medium_large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb-768x511.jpg",768,511,true],"large":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb-1024x681.jpg",1024,681,true],"1536x1536":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb.jpg",1200,798,false],"2048x2048":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb.jpg",1200,798,false],"trp-custom-language-flag":["https:\/\/bassin-arcachon.com\/wp-content\/uploads\/2026\/03\/sirtaqui-25f1a2b867251b08940e6a6adbd183eb-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/bassin-arcachon.com\/zh\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Id\u00e9alement situ\u00e9, ce loueur de v\u00e9los est \u00e0 2 minutes de la piste cyclable, dans un quartier assez peu fr\u00e9quent\u00e9, id\u00e9al pour les jeunes p\u00e9daleurs. Profitez d&rsquo;une balade immersive \u00e0 [&hellip;]","_links":{"self":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/velo_cpt\/59730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/velo_cpt"}],"about":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/types\/velo_cpt"}],"version-history":[{"count":1,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/velo_cpt\/59730\/revisions"}],"predecessor-version":[{"id":60651,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/velo_cpt\/59730\/revisions\/60651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media\/240475"}],"wp:attachment":[{"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/media?parent=59730"}],"wp:term":[{"taxonomy":"ville","embeddable":true,"href":"https:\/\/bassin-arcachon.com\/zh\/wp-json\/wp\/v2\/ville?post=59730"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}